{"id":605,"date":"2015-10-26T16:17:54","date_gmt":"2015-10-26T16:17:54","guid":{"rendered":"http:\/\/www.sanfabiano.com\/it\/?page_id=605"},"modified":"2020-09-24T12:48:24","modified_gmt":"2020-09-24T12:48:24","slug":"info-agriturismo","status":"publish","type":"page","link":"https:\/\/sanfabiano.com\/it\/info-agriturismo\/","title":{"rendered":"Info &#038; Contatti"},"content":{"rendered":"<p>[vc_row full_width=&#8221;stretch_row&#8221; css=&#8221;.vc_custom_1575545780590{margin-top: -50px !important;padding-top: 200px !important;padding-bottom: 150px !important;background-image: url(http:\/\/sanfabiano.com\/wp-content\/uploads\/2019\/12\/san-fabiano-copertina-3.jpg?id=4854) !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221; el_class=&#8221;mobile_row_hide&#8221;][vc_column offset=&#8221;vc_hidden-sm vc_hidden-xs&#8221;][vc_empty_space height=&#8221;100px&#8221;][vc_column_text]<\/p>\n<h1 style=\"text-align: center;\"><span style=\"color: #f1ebd1;\">INFO &amp; CONTATTI<\/span><\/h1>\n<p>[\/vc_column_text][vc_empty_space height=&#8221;100px&#8221;][\/vc_column][\/vc_row][vc_row content_placement=&#8221;middle&#8221; css=&#8221;.vc_custom_1528379163186{margin-right: 50px !important;margin-left: 50px !important;}&#8221;][vc_column width=&#8221;1\/3&#8243; css=&#8221;.vc_custom_1525860410238{padding-top: 20px !important;padding-bottom: 20px !important;background-color: #1f2f1b !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221;][vc_single_image image=&#8221;62&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; css=&#8221;.vc_custom_1452607707945{margin-bottom: -10px !important;}&#8221;][vc_separator color=&#8221;chino&#8221;][vc_column_text]<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #ffffff;\"><i class=\"fa fa-phone\"><\/i> Office Tel: +39 0577 372079<\/span> <span style=\"color: #ffffff;\"> <i class=\"fa fa-mobile\"><\/i> Mobile: +39 348 602 3821<\/span> <span style=\"color: #ffffff;\"> <i class=\"fa fa-mobile\"><\/i> Mobile: +39 335 683 5148<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #ffffff;\"><i class=\"fa fa-at\"><\/i>\u00a0e-mail:\u00a0<a style=\"color: #ffffff;\" href=\"mailto:info@sanfabiano.com\">info@sanfabiano.com<\/a><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #ffffff;\"><i class=\"fa fa-skype\"><\/i>\u00a0Skype: filippo4292<\/span> <span style=\"color: #ffffff;\"> <i class=\"fa fa-car\"><\/i> <a style=\"color: #ffffff;\" href=\"https:\/\/waze.to\/lr\/hsr8jujfh8\">Waze<\/a><\/span><\/p>\n<p>[\/vc_column_text][\/vc_column][vc_column width=&#8221;2\/3&#8243;][vc_column_text]<iframe loading=\"lazy\" style=\"border: 0;\" src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m18!1m12!1m3!1d3940.3370512787133!2d11.426443751449376!3d43.23062368756757!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0x132bd5f21a413af3%3A0x58061c2c03fb10dd!2sAgriturismo%20San%20Fabiano!5e1!3m2!1sit!2sit!4v1575887791867!5m2!1sit!2sit\" width=\"100%\" height=\"450\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe>[\/vc_column_text][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1528379196419{margin-right: 50px !important;margin-left: 50px !important;}&#8221;][vc_column width=&#8221;1\/2&#8243;][vc_column_text]<\/p>\n<h4 style=\"text-align: center; color: #000000;\">DALL&#8217; AEROPORTO DI ROMA<\/h4>\n<p>[\/vc_column_text][vc_column_text]<\/p>\n<p style=\"text-align: justify;\">Circa 250 km, impiegherete 3 ore scarse. Dirigetevi verso Civitavecchia, continuate verso Grosseto, e poi voltate verso Siena. Dopo aver voltato, fatti 50 km circa girate a destra a FONTAZZI, inerpicatevi sulla salita, girate a sinistra e dopo 1 km a destra verso SS2 Cassia Monteroni d&#8217;arbia. Arrivate sulla Cassia, girate a sinistra verso Siena. Entrate nel paese di Monteroni d&#8217;Arbia, dopo un benzinaio TAMOIL girate a destra per ASCIANO e subito davanti a voi vedrete due altissimi pini, e entrate in una strada bianca e la prima casa a destra \u00e8 la nostra Podernovo, ci sono cartelli con scritto San Fabiano.<\/p>\n<p>[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_column_text]<\/p>\n<h4 style=\"text-align: center; color: #000000;\">DALLA CITTA&#8217; DI ROMA<\/h4>\n<p>[\/vc_column_text][vc_column_text]<\/p>\n<p>Circa 250km tre ore scarse. Percorrete la A1 fino a Valdichiana ed uscendo tenetevi a destra fino a prendere la Perugia-Siena. Poi uscite a Rapolano e venite verso Asciano.\u00a0Passatelo e venite verso Monteroni d&#8217;Arbia. Arrivando nella valle infondo ad un lungo rettilineo troverete una freccia prima della curva e uscite piano in una strada bianca Via San Martino. il primo podere sulla destra \u00e8 il nostro! parcheggiate.<\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1528379196419{margin-right: 50px !important;margin-left: 50px !important;}&#8221;][vc_column width=&#8221;1\/2&#8243;][vc_column_text]<\/p>\n<h4 style=\"text-align: center; color: #000000;\">DA PISA AEROPORTO<\/h4>\n<p>[\/vc_column_text][vc_column_text]<\/p>\n<p style=\"text-align: justify;\">Dal\u2019aeroporto prendere per Firenze. Salire sulla A1, autostrada del sole, direzione Roma. Uscire dalla A1, a Firenze Impruneta, direzione Siena, pagare il pedaggio e girare a destra per Siena. Guidare sulla Autopalio, fino a Siena Sud. Uscire e passare sotto la autopalio, e poi a destra in direzione di Roma. Arrivare in cima, al semaforo e girare a destra per Roma. Quella e\u2019 la SR 2 Cassia. Continuate per 13 km a dritto, fin dentro il centro di Monteroni d\u2019Arbia. Passate una rotonda e passate davanti al distributore AGIP, poi a sinistra e dopo il parcheggio a destra. Tornerete sulla Via Roma, e dopo 50 metri voltate a sinistra per ASCIANO. Passato il ponte sul torrente ARBIA voltate a sinistra in mezzo a due alti pini, in una strada bianca Via San Martino168. La prima casa dopo pochi metri sulla destra \u00e8 il nostro Agriturismo San Fabiano, vedrete il grande parcheggio.<\/p>\n<p>[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_column_text]<\/p>\n<h4 style=\"text-align: center; color: #000000;\">DALLA CITTA&#8217; DI MILANO<\/h4>\n<p>[\/vc_column_text][vc_column_text]<\/p>\n<p style=\"text-align: justify;\">Uscire dalla A1, autostrada del sole, a Firenze Impruneta, pagare il pedaggio e girare a destra per Siena. Guidare sulla Autopalio, fino a Siena Sud. Uscire e passare sotto la autopalio, e poi a destra in direzione di Roma. Arrivare in cima, al semaforo e girare a destra per Roma. Quella e&#8217; la SR 2 Cassia. Continuate per 13 km fin dentro il centro di Monteroni d&#8217;Arbia. Passate una rotonda e passate davanti al distributore AGIP, poi a sinistra e dopo il parcheggio a destra. Tornerete sulla Via Roma, e dopo 50 metri voltate a sinistra per ASCIANO. Passato il ponte sul torrente ARBIA voltate a sinistra in mezzo a due alti pini, in una strada bianca. La prima casa dopo pochi metri sulla destra \u00e8 il nostro Agriturismo San Fabiano.<\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row full_width=&#8221;stretch_row&#8221; css=&#8221;.vc_custom_1575545780590{margin-top: -50px !important;padding-top: 200px !important;padding-bottom: 150px !important;background-image: url(http:\/\/sanfabiano.com\/wp-content\/uploads\/2019\/12\/san-fabiano-copertina-3.jpg?id=4854) !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221; el_class=&#8221;mobile_row_hide&#8221;][vc_column offset=&#8221;vc_hidden-sm vc_hidden-xs&#8221;][vc_empty_space height=&#8221;100px&#8221;][vc_column_text] INFO &amp; CONTATTI [\/vc_column_text][vc_empty_space height=&#8221;100px&#8221;][\/vc_column][\/vc_row][vc_row content_placement=&#8221;middle&#8221; css=&#8221;.vc_custom_1528379163186{margin-right: 50px !important;margin-left: 50px !important;}&#8221;][vc_column width=&#8221;1\/3&#8243; css=&#8221;.vc_custom_1525860410238{padding-top: 20px !important;padding-bottom: 20px !important;background-color: #1f2f1b !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221;][vc_single_image image=&#8221;62&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; css=&#8221;.vc_custom_1452607707945{margin-bottom: -10px !important;}&#8221;][vc_separator color=&#8221;chino&#8221;][vc_column_text] Office Tel: [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-605","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/sanfabiano.com\/it\/wp-json\/wp\/v2\/pages\/605\/"}],"collection":[{"href":"https:\/\/sanfabiano.com\/it\/wp-json\/wp\/v2\/pages\/"}],"about":[{"href":"https:\/\/sanfabiano.com\/it\/wp-json\/wp\/v2\/types\/page\/"}],"author":[{"embeddable":true,"href":"https:\/\/sanfabiano.com\/it\/wp-json\/wp\/v2\/users\/1\/"}],"replies":[{"embeddable":true,"href":"https:\/\/sanfabiano.com\/it\/wp-json\/wp\/v2\/comments\/?post=605"}],"version-history":[{"count":8,"href":"https:\/\/sanfabiano.com\/it\/wp-json\/wp\/v2\/pages\/605\/revisions\/"}],"predecessor-version":[{"id":5063,"href":"https:\/\/sanfabiano.com\/it\/wp-json\/wp\/v2\/pages\/605\/revisions\/5063\/"}],"wp:attachment":[{"href":"https:\/\/sanfabiano.com\/it\/wp-json\/wp\/v2\/media\/?parent=605"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}